{"id":1877,"count":35,"description":"","link":"https:\/\/www.looduspere.ee\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\/prirodnaja-kosmetika\/sredstva-ot-nasekomyx-i-klechej-ru\/","name":"\u0421\u0440\u0435\u0434\u0441\u0442\u0432\u0430 \u043e\u0442 \u043d\u0430\u0441\u0435\u043a\u043e\u043c\u044b\u0445 \u0438 \u043a\u043b\u0435\u0449\u0435\u0439","slug":"sredstva-ot-nasekomyx-i-klechej-ru","taxonomy":"product_cat","parent":1803,"meta":[],"menu_order":174,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0421\u0440\u0435\u0434\u0441\u0442\u0432\u0430 \u043e\u0442 \u043d\u0430\u0441\u0435\u043a\u043e\u043c\u044b\u0445 \u0438 \u043a\u043b\u0435\u0449\u0435\u0439 - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.looduspere.ee\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\/prirodnaja-kosmetika\/sredstva-ot-nasekomyx-i-klechej-ru\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0421\u0440\u0435\u0434\u0441\u0442\u0432\u0430 \u043e\u0442 \u043d\u0430\u0441\u0435\u043a\u043e\u043c\u044b\u0445 \u0438 \u043a\u043b\u0435\u0449\u0435\u0439 - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.looduspere.ee\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\/prirodnaja-kosmetika\/sredstva-ot-nasekomyx-i-klechej-ru\/\" \/>\n<meta property=\"og:site_name\" content=\"\u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2016\/03\/LoodusPereLogo300.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"114\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\\\/prirodnaja-kosmetika\\\/sredstva-ot-nasekomyx-i-klechej-ru\\\/\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\\\/prirodnaja-kosmetika\\\/sredstva-ot-nasekomyx-i-klechej-ru\\\/\",\"name\":\"\u0421\u0440\u0435\u0434\u0441\u0442\u0432\u0430 \u043e\u0442 \u043d\u0430\u0441\u0435\u043a\u043e\u043c\u044b\u0445 \u0438 \u043a\u043b\u0435\u0449\u0435\u0439 - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\\\/prirodnaja-kosmetika\\\/sredstva-ot-nasekomyx-i-klechej-ru\\\/#breadcrumb\"},\"inLanguage\":\"ru-EE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\\\/prirodnaja-kosmetika\\\/sredstva-ot-nasekomyx-i-klechej-ru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0434\u043e\u043c\u0430\",\"item\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041f\u0440\u0438\u0440\u043e\u0434\u043d\u0430\u044f \u043a\u043e\u0441\u043c\u0435\u0442\u0438\u043a\u0430\",\"item\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\\\/prirodnaja-kosmetika\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0421\u0440\u0435\u0434\u0441\u0442\u0432\u0430 \u043e\u0442 \u043d\u0430\u0441\u0435\u043a\u043e\u043c\u044b\u0445 \u0438 \u043a\u043b\u0435\u0449\u0435\u0439\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#website\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/\",\"name\":\"Looduspere \u00f6kopood\",\"description\":\"\u0417\u0434\u043e\u0440\u043e\u0432\u044b\u0435 \u043e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0438 \u043d\u0430\u0442\u0443\u0440\u0430\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u044b\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#organization\"},\"alternateName\":\"Looduspere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.looduspere.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-EE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#organization\",\"name\":\"Looduspere \u00f6kopood\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-EE\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/340768897_1025251132216623_8613010291235268142_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/340768897_1025251132216623_8613010291235268142_n.jpg\",\"width\":1045,\"height\":1045,\"caption\":\"Looduspere \u00f6kopood\"},\"image\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/loodusperepood\",\"https:\\\/\\\/www.instagram.com\\\/looduspere\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0421\u0440\u0435\u0434\u0441\u0442\u0432\u0430 \u043e\u0442 \u043d\u0430\u0441\u0435\u043a\u043e\u043c\u044b\u0445 \u0438 \u043a\u043b\u0435\u0449\u0435\u0439 - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.looduspere.ee\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\/prirodnaja-kosmetika\/sredstva-ot-nasekomyx-i-klechej-ru\/","og_locale":"ru_RU","og_type":"article","og_title":"\u0421\u0440\u0435\u0434\u0441\u0442\u0432\u0430 \u043e\u0442 \u043d\u0430\u0441\u0435\u043a\u043e\u043c\u044b\u0445 \u0438 \u043a\u043b\u0435\u0449\u0435\u0439 - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","og_url":"https:\/\/www.looduspere.ee\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\/prirodnaja-kosmetika\/sredstva-ot-nasekomyx-i-klechej-ru\/","og_site_name":"\u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","og_image":[{"width":300,"height":114,"url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2016\/03\/LoodusPereLogo300.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.looduspere.ee\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\/prirodnaja-kosmetika\/sredstva-ot-nasekomyx-i-klechej-ru\/","url":"https:\/\/www.looduspere.ee\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\/prirodnaja-kosmetika\/sredstva-ot-nasekomyx-i-klechej-ru\/","name":"\u0421\u0440\u0435\u0434\u0441\u0442\u0432\u0430 \u043e\u0442 \u043d\u0430\u0441\u0435\u043a\u043e\u043c\u044b\u0445 \u0438 \u043a\u043b\u0435\u0449\u0435\u0439 - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","isPartOf":{"@id":"https:\/\/www.looduspere.ee\/#website"},"breadcrumb":{"@id":"https:\/\/www.looduspere.ee\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\/prirodnaja-kosmetika\/sredstva-ot-nasekomyx-i-klechej-ru\/#breadcrumb"},"inLanguage":"ru-EE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.looduspere.ee\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\/prirodnaja-kosmetika\/sredstva-ot-nasekomyx-i-klechej-ru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0434\u043e\u043c\u0430","item":"https:\/\/www.looduspere.ee\/ru\/"},{"@type":"ListItem","position":2,"name":"\u041f\u0440\u0438\u0440\u043e\u0434\u043d\u0430\u044f \u043a\u043e\u0441\u043c\u0435\u0442\u0438\u043a\u0430","item":"https:\/\/www.looduspere.ee\/ru\/\u043a\u0430\u0442\u0435\u0433\u043e\u0440\u0438\u044f-\u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\/prirodnaja-kosmetika\/"},{"@type":"ListItem","position":3,"name":"\u0421\u0440\u0435\u0434\u0441\u0442\u0432\u0430 \u043e\u0442 \u043d\u0430\u0441\u0435\u043a\u043e\u043c\u044b\u0445 \u0438 \u043a\u043b\u0435\u0449\u0435\u0439"}]},{"@type":"WebSite","@id":"https:\/\/www.looduspere.ee\/#website","url":"https:\/\/www.looduspere.ee\/","name":"Looduspere \u00f6kopood","description":"\u0417\u0434\u043e\u0440\u043e\u0432\u044b\u0435 \u043e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0438 \u043d\u0430\u0442\u0443\u0440\u0430\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u044b","publisher":{"@id":"https:\/\/www.looduspere.ee\/#organization"},"alternateName":"Looduspere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.looduspere.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-EE"},{"@type":"Organization","@id":"https:\/\/www.looduspere.ee\/#organization","name":"Looduspere \u00f6kopood","url":"https:\/\/www.looduspere.ee\/","logo":{"@type":"ImageObject","inLanguage":"ru-EE","@id":"https:\/\/www.looduspere.ee\/#\/schema\/logo\/image\/","url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2025\/01\/340768897_1025251132216623_8613010291235268142_n.jpg","contentUrl":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2025\/01\/340768897_1025251132216623_8613010291235268142_n.jpg","width":1045,"height":1045,"caption":"Looduspere \u00f6kopood"},"image":{"@id":"https:\/\/www.looduspere.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loodusperepood","https:\/\/www.instagram.com\/looduspere\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/product_cat\/1877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/product_cat\/1803"}],"wp:post_type":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/product?product_cat=1877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}