{"id":187325,"date":"2023-09-03T15:33:17","date_gmt":"2024-09-03T12:33:17","guid":{"rendered":"https:\/\/www.looduspere.ee\/?post_type=product&#038;p=187325"},"modified":"2024-09-03T15:39:03","modified_gmt":"2024-09-03T12:39:03","slug":"weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri","status":"publish","type":"product","link":"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\/","title":{"rendered":"Weleda \u041a\u0430\u043b\u0435\u043d\u0434\u0443\u043b\u0430 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e 100\u043c\u043b"},"content":{"rendered":"<div class=\"text col-xs-12 col-mm-10 offset-xs-0 offset-mm-1 mt-4\">\n<p>\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u0430\u043d \u0434\u043b\u044f \u0447\u0443\u0432\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0439 \u0438 \u043d\u0435\u0436\u043d\u043e\u0439 \u043a\u043e\u0436\u0438, \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u0438\u0432\u0430\u0435\u0442 \u0435\u0441\u0442\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0435 \u0444\u0443\u043d\u043a\u0446\u0438\u0438 \u043a\u043e\u0436\u0438, \u0442\u0430\u043a\u0438\u0435 \u043a\u0430\u043a \u0431\u0430\u043b\u0430\u043d\u0441 \u043c\u0430\u0441\u043b\u0430 \u0438 \u0432\u043b\u0430\u0433\u0438, \u043e\u0431\u0440\u0430\u0437\u0443\u0435\u0442 \u043d\u0430 \u043a\u043e\u0436\u0435 \u0437\u0430\u0449\u0438\u0442\u043d\u044b\u0439 \u0442\u0435\u043f\u043b\u043e\u0432\u043e\u0439 \u0441\u043b\u043e\u0439. \u042d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u0431\u0430\u0440\u0445\u0430\u0442\u0446\u0435\u0432 \u0438 \u0440\u043e\u043c\u0430\u0448\u043a\u0438 \u0432 \u0441\u043e\u0441\u0442\u0430\u0432\u0435 \u0443\u0441\u043f\u043e\u043a\u0430\u0438\u0432\u0430\u0435\u0442, \u0430 \u044d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u043b\u0438\u0441\u0442\u044c\u0435\u0432 \u0431\u0435\u0440\u0435\u0437\u044b \u0432\u044b\u0432\u043e\u0434\u0438\u0442 \u0442\u043e\u043a\u0441\u0438\u043d\u044b, \u0443\u0441\u043f\u043e\u043a\u0430\u0438\u0432\u0430\u0435\u0442 \u0438 \u0443\u0445\u0430\u0436\u0438\u0432\u0430\u0435\u0442 \u0437\u0430 \u043a\u043e\u0436\u0435\u0439. \u0411\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u043b\u0435\u0433\u043a\u043e\u043c\u0443 \u0441\u043e\u0441\u0442\u0430\u0432\u0443, \u043e\u0441\u043d\u043e\u0432\u043d\u044b\u043c \u043a\u043e\u043c\u043f\u043e\u043d\u0435\u043d\u0442\u043e\u043c \u043a\u043e\u0442\u043e\u0440\u043e\u0433\u043e \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043f\u043e\u0434\u0441\u043e\u043b\u043d\u0435\u0447\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e, \u043e\u043d\u043e \u043e\u0441\u043e\u0431\u0435\u043d\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0433\u043e \u043c\u0430\u0441\u043b\u0430.<\/p>\n<p>\u042d\u0444\u0444\u0435\u043a\u0442<\/p>\n<p>\u0421\u043c\u044f\u0433\u0447\u0430\u0435\u0442 \u0438 \u043f\u0438\u0442\u0430\u0435\u0442. \u0414\u0435\u0440\u043c\u0430\u0442\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u0438 \u043f\u0440\u043e\u0442\u0435\u0441\u0442\u0438\u0440\u043e\u0432\u0430\u043d\u043e. \u0411\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e \u0434\u043b\u044f \u043a\u043e\u0436\u0438.<\/p>\n<p>\u0418\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u043d\u0438\u0435<\/p>\n<p>\u041d\u0430\u043d\u0435\u0441\u0438\u0442\u0435 \u0442\u043e\u043d\u043a\u0438\u043c \u0441\u043b\u043e\u0435\u043c \u043d\u0430 \u0441\u043b\u0435\u0433\u043a\u0430 \u0432\u043b\u0430\u0436\u043d\u0443\u044e \u043a\u043e\u0436\u0443 \u043f\u043e\u0441\u043b\u0435 \u0434\u0443\u0448\u0430 \u0438\u043b\u0438 \u0432\u0430\u043d\u043d\u044b \u0438 \u0430\u043a\u043a\u0443\u0440\u0430\u0442\u043d\u043e \u043c\u0430\u0441\u0441\u0438\u0440\u0443\u0439\u0442\u0435. \u041c\u0430\u0441\u043b\u043e \u043b\u0435\u0433\u043a\u043e \u0440\u0430\u0441\u043f\u0440\u0435\u0434\u0435\u043b\u044f\u0435\u0442\u0441\u044f \u0438 \u0431\u044b\u0441\u0442\u0440\u043e \u0432\u043f\u0438\u0442\u044b\u0432\u0430\u0435\u0442\u0441\u044f \u0432 \u043a\u043e\u0436\u0443. \u0418\u0434\u0435\u0430\u043b\u044c\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0433\u043e \u043c\u0430\u0441\u043b\u0430.<\/p>\n<p>\u0418\u043d\u0433\u0440\u0435\u0434\u0438\u0435\u043d\u0442\u044b:<\/p>\n<p>\u041f\u043e\u0434\u0441\u043e\u043b\u043d\u0435\u0447\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e \u042d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u043b\u0438\u0441\u0442\u044c\u0435\u0432 \u0431\u0435\u0440\u0435\u0437\u044b \u042d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u043a\u0430\u043b\u0435\u043d\u0434\u0443\u043b\u044b \u042d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u0446\u0432\u0435\u0442\u043a\u043e\u0432 \u0440\u043e\u043c\u0430\u0448\u043a\u0438 \u041f\u0430\u0440\u0444\u044e\u043c \u041b\u0438\u043c\u043e\u043d\u0435\u043d \u041b\u0438\u043d\u0430\u043b\u043e\u043e\u043b \u0426\u0438\u0442\u0440\u043e\u043d\u0435\u043b\u043b\u043e\u043b \u0413\u0435\u0440\u0430\u043d\u0438\u043e\u043b \u0426\u0438\u0442\u0440\u0430\u043b\u044c<\/p>\n<p>\u0426\u0435\u043d\u0430 \u0437\u0430 1 \u043b: 185,8 \u0435\u0432\u0440\u043e.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u0430\u043d \u0434\u043b\u044f \u0447\u0443\u0432\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0439 \u0438 \u043d\u0435\u0436\u043d\u043e\u0439 \u043a\u043e\u0436\u0438, \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u0438\u0432\u0430\u0435\u0442 \u0435\u0441\u0442\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0435 \u0444\u0443\u043d\u043a\u0446\u0438\u0438 \u043a\u043e\u0436\u0438, \u0442\u0430\u043a\u0438\u0435 \u043a\u0430\u043a \u0431\u0430\u043b\u0430\u043d\u0441 \u043c\u0430\u0441\u043b\u0430 \u0438 \u0432\u043b\u0430\u0433\u0438, \u043e\u0431\u0440\u0430\u0437\u0443\u0435\u0442 \u043d\u0430 \u043a\u043e\u0436\u0435 \u0437\u0430\u0449\u0438\u0442\u043d\u044b\u0439 \u0442\u0435\u043f\u043b\u043e\u0432\u043e\u0439 \u0441\u043b\u043e\u0439. \u042d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u0431\u0430\u0440\u0445\u0430\u0442\u0446\u0435\u0432 \u0438 \u0440\u043e\u043c\u0430\u0448\u043a\u0438 \u0432 \u0441\u043e\u0441\u0442\u0430\u0432\u0435 \u0443\u0441\u043f\u043e\u043a\u0430\u0438\u0432\u0430\u0435\u0442, \u0430 \u044d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u043b\u0438\u0441\u0442\u044c\u0435\u0432 \u0431\u0435\u0440\u0435\u0437\u044b \u0432\u044b\u0432\u043e\u0434\u0438\u0442 \u0442\u043e\u043a\u0441\u0438\u043d\u044b, \u0443\u0441\u043f\u043e\u043a\u0430\u0438\u0432\u0430\u0435\u0442 \u0438 \u0443\u0445\u0430\u0436\u0438\u0432\u0430\u0435\u0442 \u0437\u0430 \u043a\u043e\u0436\u0435\u0439. \u0411\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u043b\u0435\u0433\u043a\u043e\u043c\u0443 \u0441\u043e\u0441\u0442\u0430\u0432\u0443, \u043e\u0441\u043d\u043e\u0432\u043d\u044b\u043c \u043a\u043e\u043c\u043f\u043e\u043d\u0435\u043d\u0442\u043e\u043c \u043a\u043e\u0442\u043e\u0440\u043e\u0433\u043e \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043f\u043e\u0434\u0441\u043e\u043b\u043d\u0435\u0447\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e, \u043e\u043d\u043e \u043e\u0441\u043e\u0431\u0435\u043d\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0433\u043e \u043c\u0430\u0441\u043b\u0430. \u042d\u0444\u0444\u0435\u043a\u0442 \u0421\u043c\u044f\u0433\u0447\u0430\u0435\u0442 \u0438 \u043f\u0438\u0442\u0430\u0435\u0442.&hellip;<\/p>\n","protected":false},"featured_media":187328,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[447,1622],"product_tag":[],"class_list":["post-187325","product","type-product","status-publish","has-post-thumbnail","product_cat-looduskosmeetika","product_cat-kehahooldus","first","onbackorder","shipping-taxable","purchasable","product-type-simple","col-xs-6 col-sm-4","col-md-3 col-lg-3","un-4-cols"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weleda \u041a\u0430\u043b\u0435\u043d\u0434\u0443\u043b\u0430 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e 100\u043c\u043b - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-\u043c\u0430\u0441\u043b\u043e-\u043e\u0442-\u0446\u0435\u043b\u043b\u044e\u043b\u0438\u0442\u0430-100\u043c\u043b-kopeeri\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weleda \u041a\u0430\u043b\u0435\u043d\u0434\u0443\u043b\u0430 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e 100\u043c\u043b - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere\" \/>\n<meta property=\"og:description\" content=\"\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u0430\u043d \u0434\u043b\u044f \u0447\u0443\u0432\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0439 \u0438 \u043d\u0435\u0436\u043d\u043e\u0439 \u043a\u043e\u0436\u0438, \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u0438\u0432\u0430\u0435\u0442 \u0435\u0441\u0442\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0435 \u0444\u0443\u043d\u043a\u0446\u0438\u0438 \u043a\u043e\u0436\u0438, \u0442\u0430\u043a\u0438\u0435 \u043a\u0430\u043a \u0431\u0430\u043b\u0430\u043d\u0441 \u043c\u0430\u0441\u043b\u0430 \u0438 \u0432\u043b\u0430\u0433\u0438, \u043e\u0431\u0440\u0430\u0437\u0443\u0435\u0442 \u043d\u0430 \u043a\u043e\u0436\u0435 \u0437\u0430\u0449\u0438\u0442\u043d\u044b\u0439 \u0442\u0435\u043f\u043b\u043e\u0432\u043e\u0439 \u0441\u043b\u043e\u0439. \u042d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u0431\u0430\u0440\u0445\u0430\u0442\u0446\u0435\u0432 \u0438 \u0440\u043e\u043c\u0430\u0448\u043a\u0438 \u0432 \u0441\u043e\u0441\u0442\u0430\u0432\u0435 \u0443\u0441\u043f\u043e\u043a\u0430\u0438\u0432\u0430\u0435\u0442, \u0430 \u044d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u043b\u0438\u0441\u0442\u044c\u0435\u0432 \u0431\u0435\u0440\u0435\u0437\u044b \u0432\u044b\u0432\u043e\u0434\u0438\u0442 \u0442\u043e\u043a\u0441\u0438\u043d\u044b, \u0443\u0441\u043f\u043e\u043a\u0430\u0438\u0432\u0430\u0435\u0442 \u0438 \u0443\u0445\u0430\u0436\u0438\u0432\u0430\u0435\u0442 \u0437\u0430 \u043a\u043e\u0436\u0435\u0439. \u0411\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u043b\u0435\u0433\u043a\u043e\u043c\u0443 \u0441\u043e\u0441\u0442\u0430\u0432\u0443, \u043e\u0441\u043d\u043e\u0432\u043d\u044b\u043c \u043a\u043e\u043c\u043f\u043e\u043d\u0435\u043d\u0442\u043e\u043c \u043a\u043e\u0442\u043e\u0440\u043e\u0433\u043e \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043f\u043e\u0434\u0441\u043e\u043b\u043d\u0435\u0447\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e, \u043e\u043d\u043e \u043e\u0441\u043e\u0431\u0435\u043d\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0433\u043e \u043c\u0430\u0441\u043b\u0430. \u042d\u0444\u0444\u0435\u043a\u0442 \u0421\u043c\u044f\u0433\u0447\u0430\u0435\u0442 \u0438 \u043f\u0438\u0442\u0430\u0435\u0442.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-\u043c\u0430\u0441\u043b\u043e-\u043e\u0442-\u0446\u0435\u043b\u043b\u044e\u043b\u0438\u0442\u0430-100\u043c\u043b-kopeeri\/\" \/>\n<meta property=\"og:site_name\" content=\"\u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/loodusperepood\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-03T12:39:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2016\/03\/LoodusPereLogo300.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"114\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u0441\u0442\u0430\u0442\u044c\u044f\\\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\\\/\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u0441\u0442\u0430\u0442\u044c\u044f\\\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\\\/\",\"name\":\"Weleda \u041a\u0430\u043b\u0435\u043d\u0434\u0443\u043b\u0430 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e 100\u043c\u043b - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u0441\u0442\u0430\u0442\u044c\u044f\\\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u0441\u0442\u0430\u0442\u044c\u044f\\\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/weleda_productFourBySeven-13.avif\",\"datePublished\":\"2024-09-03T12:33:17+00:00\",\"dateModified\":\"2024-09-03T12:39:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u0441\u0442\u0430\u0442\u044c\u044f\\\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\\\/#breadcrumb\"},\"inLanguage\":\"ru-EE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u0441\u0442\u0430\u0442\u044c\u044f\\\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-EE\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u0441\u0442\u0430\u0442\u044c\u044f\\\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/weleda_productFourBySeven-13.avif\",\"contentUrl\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/weleda_productFourBySeven-13.avif\",\"width\":384,\"height\":672},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\u0441\u0442\u0430\u0442\u044c\u044f\\\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0434\u043e\u043c\u0430\",\"item\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0422\u043e\u0432\u0430\u0440\u044b\",\"item\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/%d1%82%d0%be%d0%b2%d0%b0%d1%80%d1%8b\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weleda \u041a\u0430\u043b\u0435\u043d\u0434\u0443\u043b\u0430 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e 100\u043c\u043b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#website\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/\",\"name\":\"Looduspere \u00f6kopood\",\"description\":\"\u0417\u0434\u043e\u0440\u043e\u0432\u044b\u0435 \u043e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0438 \u043d\u0430\u0442\u0443\u0440\u0430\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u044b\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#organization\"},\"alternateName\":\"Looduspere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.looduspere.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-EE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#organization\",\"name\":\"Looduspere \u00f6kopood\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-EE\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/340768897_1025251132216623_8613010291235268142_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/340768897_1025251132216623_8613010291235268142_n.jpg\",\"width\":1045,\"height\":1045,\"caption\":\"Looduspere \u00f6kopood\"},\"image\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/loodusperepood\",\"https:\\\/\\\/www.instagram.com\\\/looduspere\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weleda \u041a\u0430\u043b\u0435\u043d\u0434\u0443\u043b\u0430 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e 100\u043c\u043b - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-\u043c\u0430\u0441\u043b\u043e-\u043e\u0442-\u0446\u0435\u043b\u043b\u044e\u043b\u0438\u0442\u0430-100\u043c\u043b-kopeeri\/","og_locale":"ru_RU","og_type":"article","og_title":"Weleda \u041a\u0430\u043b\u0435\u043d\u0434\u0443\u043b\u0430 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e 100\u043c\u043b - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","og_description":"\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u0430\u043d \u0434\u043b\u044f \u0447\u0443\u0432\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0439 \u0438 \u043d\u0435\u0436\u043d\u043e\u0439 \u043a\u043e\u0436\u0438, \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u0438\u0432\u0430\u0435\u0442 \u0435\u0441\u0442\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0435 \u0444\u0443\u043d\u043a\u0446\u0438\u0438 \u043a\u043e\u0436\u0438, \u0442\u0430\u043a\u0438\u0435 \u043a\u0430\u043a \u0431\u0430\u043b\u0430\u043d\u0441 \u043c\u0430\u0441\u043b\u0430 \u0438 \u0432\u043b\u0430\u0433\u0438, \u043e\u0431\u0440\u0430\u0437\u0443\u0435\u0442 \u043d\u0430 \u043a\u043e\u0436\u0435 \u0437\u0430\u0449\u0438\u0442\u043d\u044b\u0439 \u0442\u0435\u043f\u043b\u043e\u0432\u043e\u0439 \u0441\u043b\u043e\u0439. \u042d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u0431\u0430\u0440\u0445\u0430\u0442\u0446\u0435\u0432 \u0438 \u0440\u043e\u043c\u0430\u0448\u043a\u0438 \u0432 \u0441\u043e\u0441\u0442\u0430\u0432\u0435 \u0443\u0441\u043f\u043e\u043a\u0430\u0438\u0432\u0430\u0435\u0442, \u0430 \u044d\u043a\u0441\u0442\u0440\u0430\u043a\u0442 \u043b\u0438\u0441\u0442\u044c\u0435\u0432 \u0431\u0435\u0440\u0435\u0437\u044b \u0432\u044b\u0432\u043e\u0434\u0438\u0442 \u0442\u043e\u043a\u0441\u0438\u043d\u044b, \u0443\u0441\u043f\u043e\u043a\u0430\u0438\u0432\u0430\u0435\u0442 \u0438 \u0443\u0445\u0430\u0436\u0438\u0432\u0430\u0435\u0442 \u0437\u0430 \u043a\u043e\u0436\u0435\u0439. \u0411\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u043b\u0435\u0433\u043a\u043e\u043c\u0443 \u0441\u043e\u0441\u0442\u0430\u0432\u0443, \u043e\u0441\u043d\u043e\u0432\u043d\u044b\u043c \u043a\u043e\u043c\u043f\u043e\u043d\u0435\u043d\u0442\u043e\u043c \u043a\u043e\u0442\u043e\u0440\u043e\u0433\u043e \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043f\u043e\u0434\u0441\u043e\u043b\u043d\u0435\u0447\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e, \u043e\u043d\u043e \u043e\u0441\u043e\u0431\u0435\u043d\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0433\u043e \u043c\u0430\u0441\u043b\u0430. \u042d\u0444\u0444\u0435\u043a\u0442 \u0421\u043c\u044f\u0433\u0447\u0430\u0435\u0442 \u0438 \u043f\u0438\u0442\u0430\u0435\u0442.&hellip;","og_url":"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-\u043c\u0430\u0441\u043b\u043e-\u043e\u0442-\u0446\u0435\u043b\u043b\u044e\u043b\u0438\u0442\u0430-100\u043c\u043b-kopeeri\/","og_site_name":"\u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","article_publisher":"https:\/\/www.facebook.com\/loodusperepood","article_modified_time":"2024-09-03T12:39:03+00:00","og_image":[{"width":300,"height":114,"url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2016\/03\/LoodusPereLogo300.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\/","url":"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\/","name":"Weleda \u041a\u0430\u043b\u0435\u043d\u0434\u0443\u043b\u0430 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e 100\u043c\u043b - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","isPartOf":{"@id":"https:\/\/www.looduspere.ee\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\/#primaryimage"},"image":{"@id":"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2024\/09\/weleda_productFourBySeven-13.avif","datePublished":"2024-09-03T12:33:17+00:00","dateModified":"2024-09-03T12:39:03+00:00","breadcrumb":{"@id":"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\/#breadcrumb"},"inLanguage":"ru-EE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\/"]}]},{"@type":"ImageObject","inLanguage":"ru-EE","@id":"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\/#primaryimage","url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2024\/09\/weleda_productFourBySeven-13.avif","contentUrl":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2024\/09\/weleda_productFourBySeven-13.avif","width":384,"height":672},{"@type":"BreadcrumbList","@id":"https:\/\/www.looduspere.ee\/ru\/\u0441\u0442\u0430\u0442\u044c\u044f\/weleda-%d0%bc%d0%b0%d1%81%d0%bb%d0%be-%d0%be%d1%82-%d1%86%d0%b5%d0%bb%d0%bb%d1%8e%d0%bb%d0%b8%d1%82%d0%b0-100%d0%bc%d0%bb-kopeeri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0434\u043e\u043c\u0430","item":"https:\/\/www.looduspere.ee\/ru\/"},{"@type":"ListItem","position":2,"name":"\u0422\u043e\u0432\u0430\u0440\u044b","item":"https:\/\/www.looduspere.ee\/ru\/%d1%82%d0%be%d0%b2%d0%b0%d1%80%d1%8b\/"},{"@type":"ListItem","position":3,"name":"Weleda \u041a\u0430\u043b\u0435\u043d\u0434\u0443\u043b\u0430 \u043c\u0430\u0441\u0441\u0430\u0436\u043d\u043e\u0435 \u043c\u0430\u0441\u043b\u043e 100\u043c\u043b"}]},{"@type":"WebSite","@id":"https:\/\/www.looduspere.ee\/#website","url":"https:\/\/www.looduspere.ee\/","name":"Looduspere \u00f6kopood","description":"\u0417\u0434\u043e\u0440\u043e\u0432\u044b\u0435 \u043e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0438 \u043d\u0430\u0442\u0443\u0440\u0430\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u044b","publisher":{"@id":"https:\/\/www.looduspere.ee\/#organization"},"alternateName":"Looduspere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.looduspere.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-EE"},{"@type":"Organization","@id":"https:\/\/www.looduspere.ee\/#organization","name":"Looduspere \u00f6kopood","url":"https:\/\/www.looduspere.ee\/","logo":{"@type":"ImageObject","inLanguage":"ru-EE","@id":"https:\/\/www.looduspere.ee\/#\/schema\/logo\/image\/","url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2025\/01\/340768897_1025251132216623_8613010291235268142_n.jpg","contentUrl":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2025\/01\/340768897_1025251132216623_8613010291235268142_n.jpg","width":1045,"height":1045,"caption":"Looduspere \u00f6kopood"},"image":{"@id":"https:\/\/www.looduspere.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loodusperepood","https:\/\/www.instagram.com\/looduspere\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/product\/187325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/comments?post=187325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/media\/187328"}],"wp:attachment":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/media?parent=187325"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/product_cat?post=187325"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/product_tag?post=187325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}