{"id":136106,"date":"2021-09-16T15:58:42","date_gmt":"2021-09-16T12:58:42","guid":{"rendered":"https:\/\/www.looduspere.ee\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\/"},"modified":"2021-09-16T15:58:42","modified_gmt":"2021-09-16T12:58:42","slug":"%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c","status":"publish","type":"page","link":"https:\/\/www.looduspere.ee\/ru\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\/","title":{"rendered":"\u041c\u043e\u044f \u0443\u0447\u0435\u0442\u043d\u0430\u044f \u0437\u0430\u043f\u0438\u0441\u044c"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":672,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-136106","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u041c\u043e\u044f \u0443\u0447\u0435\u0442\u043d\u0430\u044f \u0437\u0430\u043f\u0438\u0441\u044c - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.looduspere.ee\/ru\/\u043c\u043e\u044f-\u0443\u0447\u0435\u0442\u043d\u0430\u044f-\u0437\u0430\u043f\u0438\u0441\u044c\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u041c\u043e\u044f \u0443\u0447\u0435\u0442\u043d\u0430\u044f \u0437\u0430\u043f\u0438\u0441\u044c - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.looduspere.ee\/ru\/\u043c\u043e\u044f-\u0443\u0447\u0435\u0442\u043d\u0430\u044f-\u0437\u0430\u043f\u0438\u0441\u044c\/\" \/>\n<meta property=\"og:site_name\" content=\"\u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/loodusperepood\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2016\/03\/LoodusPereLogo300.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"114\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\\\/\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\\\/\",\"name\":\"\u041c\u043e\u044f \u0443\u0447\u0435\u0442\u043d\u0430\u044f \u0437\u0430\u043f\u0438\u0441\u044c - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#website\"},\"datePublished\":\"2021-09-16T12:58:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\\\/#breadcrumb\"},\"inLanguage\":\"ru-EE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0434\u043e\u043c\u0430\",\"item\":\"https:\\\/\\\/www.looduspere.ee\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041c\u043e\u044f \u0443\u0447\u0435\u0442\u043d\u0430\u044f \u0437\u0430\u043f\u0438\u0441\u044c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#website\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/\",\"name\":\"Looduspere \u00f6kopood\",\"description\":\"\u0417\u0434\u043e\u0440\u043e\u0432\u044b\u0435 \u043e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0438 \u043d\u0430\u0442\u0443\u0440\u0430\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u044b\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#organization\"},\"alternateName\":\"Looduspere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.looduspere.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-EE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#organization\",\"name\":\"Looduspere \u00f6kopood\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-EE\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/340768897_1025251132216623_8613010291235268142_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/340768897_1025251132216623_8613010291235268142_n.jpg\",\"width\":1045,\"height\":1045,\"caption\":\"Looduspere \u00f6kopood\"},\"image\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/loodusperepood\",\"https:\\\/\\\/www.instagram.com\\\/looduspere\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041c\u043e\u044f \u0443\u0447\u0435\u0442\u043d\u0430\u044f \u0437\u0430\u043f\u0438\u0441\u044c - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.looduspere.ee\/ru\/\u043c\u043e\u044f-\u0443\u0447\u0435\u0442\u043d\u0430\u044f-\u0437\u0430\u043f\u0438\u0441\u044c\/","og_locale":"ru_RU","og_type":"article","og_title":"\u041c\u043e\u044f \u0443\u0447\u0435\u0442\u043d\u0430\u044f \u0437\u0430\u043f\u0438\u0441\u044c - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","og_url":"https:\/\/www.looduspere.ee\/ru\/\u043c\u043e\u044f-\u0443\u0447\u0435\u0442\u043d\u0430\u044f-\u0437\u0430\u043f\u0438\u0441\u044c\/","og_site_name":"\u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","article_publisher":"https:\/\/www.facebook.com\/loodusperepood","og_image":[{"width":300,"height":114,"url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2016\/03\/LoodusPereLogo300.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.looduspere.ee\/ru\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\/","url":"https:\/\/www.looduspere.ee\/ru\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\/","name":"\u041c\u043e\u044f \u0443\u0447\u0435\u0442\u043d\u0430\u044f \u0437\u0430\u043f\u0438\u0441\u044c - \u041e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043c\u0430\u0433\u0430\u0437\u0438\u043d Looduspere","isPartOf":{"@id":"https:\/\/www.looduspere.ee\/#website"},"datePublished":"2021-09-16T12:58:42+00:00","breadcrumb":{"@id":"https:\/\/www.looduspere.ee\/ru\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\/#breadcrumb"},"inLanguage":"ru-EE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.looduspere.ee\/ru\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.looduspere.ee\/ru\/%d0%bc%d0%be%d1%8f-%d1%83%d1%87%d0%b5%d1%82%d0%bd%d0%b0%d1%8f-%d0%b7%d0%b0%d0%bf%d0%b8%d1%81%d1%8c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0434\u043e\u043c\u0430","item":"https:\/\/www.looduspere.ee\/ru\/"},{"@type":"ListItem","position":2,"name":"\u041c\u043e\u044f \u0443\u0447\u0435\u0442\u043d\u0430\u044f \u0437\u0430\u043f\u0438\u0441\u044c"}]},{"@type":"WebSite","@id":"https:\/\/www.looduspere.ee\/#website","url":"https:\/\/www.looduspere.ee\/","name":"Looduspere \u00f6kopood","description":"\u0417\u0434\u043e\u0440\u043e\u0432\u044b\u0435 \u043e\u0440\u0433\u0430\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0438 \u043d\u0430\u0442\u0443\u0440\u0430\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u044b","publisher":{"@id":"https:\/\/www.looduspere.ee\/#organization"},"alternateName":"Looduspere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.looduspere.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-EE"},{"@type":"Organization","@id":"https:\/\/www.looduspere.ee\/#organization","name":"Looduspere \u00f6kopood","url":"https:\/\/www.looduspere.ee\/","logo":{"@type":"ImageObject","inLanguage":"ru-EE","@id":"https:\/\/www.looduspere.ee\/#\/schema\/logo\/image\/","url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2025\/01\/340768897_1025251132216623_8613010291235268142_n.jpg","contentUrl":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2025\/01\/340768897_1025251132216623_8613010291235268142_n.jpg","width":1045,"height":1045,"caption":"Looduspere \u00f6kopood"},"image":{"@id":"https:\/\/www.looduspere.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loodusperepood","https:\/\/www.instagram.com\/looduspere\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/pages\/136106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/users\/672"}],"replies":[{"embeddable":true,"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/comments?post=136106"}],"version-history":[{"count":0,"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/pages\/136106\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.looduspere.ee\/ru\/wp-json\/wp\/v2\/media?parent=136106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}