{"id":966,"count":0,"description":"","link":"https:\/\/www.looduspere.ee\/en\/product-category\/art-and-office-supplies\/egg-dyes\/","name":"Egg Dyes","slug":"egg-dyes","taxonomy":"product_cat","parent":1157,"meta":[],"menu_order":260,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Egg Dyes - Looduspere Organic Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.looduspere.ee\/en\/product-category\/art-and-office-supplies\/egg-dyes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Egg Dyes - Looduspere Organic Shop\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.looduspere.ee\/en\/product-category\/art-and-office-supplies\/egg-dyes\/\" \/>\n<meta property=\"og:site_name\" content=\"Looduspere Organic Shop\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2016\/03\/LoodusPereLogo300.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"114\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product-category\\\/art-and-office-supplies\\\/egg-dyes\\\/\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product-category\\\/art-and-office-supplies\\\/egg-dyes\\\/\",\"name\":\"Egg Dyes - Looduspere Organic Shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product-category\\\/art-and-office-supplies\\\/egg-dyes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product-category\\\/art-and-office-supplies\\\/egg-dyes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art and office supplies\",\"item\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product-category\\\/art-and-office-supplies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Egg Dyes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#website\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/\",\"name\":\"Looduspere \u00f6kopood\",\"description\":\"Healthy organic and natural products\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#organization\"},\"alternateName\":\"Looduspere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.looduspere.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#organization\",\"name\":\"Looduspere \u00f6kopood\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/340768897_1025251132216623_8613010291235268142_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/340768897_1025251132216623_8613010291235268142_n.jpg\",\"width\":1045,\"height\":1045,\"caption\":\"Looduspere \u00f6kopood\"},\"image\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/loodusperepood\",\"https:\\\/\\\/www.instagram.com\\\/looduspere\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Egg Dyes - Looduspere Organic Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.looduspere.ee\/en\/product-category\/art-and-office-supplies\/egg-dyes\/","og_locale":"en_US","og_type":"article","og_title":"Egg Dyes - Looduspere Organic Shop","og_url":"https:\/\/www.looduspere.ee\/en\/product-category\/art-and-office-supplies\/egg-dyes\/","og_site_name":"Looduspere Organic Shop","og_image":[{"width":300,"height":114,"url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2016\/03\/LoodusPereLogo300.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.looduspere.ee\/en\/product-category\/art-and-office-supplies\/egg-dyes\/","url":"https:\/\/www.looduspere.ee\/en\/product-category\/art-and-office-supplies\/egg-dyes\/","name":"Egg Dyes - Looduspere Organic Shop","isPartOf":{"@id":"https:\/\/www.looduspere.ee\/#website"},"breadcrumb":{"@id":"https:\/\/www.looduspere.ee\/en\/product-category\/art-and-office-supplies\/egg-dyes\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.looduspere.ee\/en\/product-category\/art-and-office-supplies\/egg-dyes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.looduspere.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Art and office supplies","item":"https:\/\/www.looduspere.ee\/en\/product-category\/art-and-office-supplies\/"},{"@type":"ListItem","position":3,"name":"Egg Dyes"}]},{"@type":"WebSite","@id":"https:\/\/www.looduspere.ee\/#website","url":"https:\/\/www.looduspere.ee\/","name":"Looduspere \u00f6kopood","description":"Healthy organic and natural products","publisher":{"@id":"https:\/\/www.looduspere.ee\/#organization"},"alternateName":"Looduspere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.looduspere.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.looduspere.ee\/#organization","name":"Looduspere \u00f6kopood","url":"https:\/\/www.looduspere.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.looduspere.ee\/#\/schema\/logo\/image\/","url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2025\/01\/340768897_1025251132216623_8613010291235268142_n.jpg","contentUrl":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2025\/01\/340768897_1025251132216623_8613010291235268142_n.jpg","width":1045,"height":1045,"caption":"Looduspere \u00f6kopood"},"image":{"@id":"https:\/\/www.looduspere.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loodusperepood","https:\/\/www.instagram.com\/looduspere\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/product_cat\/966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/product_cat\/1157"}],"wp:post_type":[{"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/product?product_cat=966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}