{"id":62502,"date":"2015-11-02T15:30:26","date_gmt":"2016-06-30T12:04:20","guid":{"rendered":"http:\/\/www.looduspere.ee\/en\/?post_type=product&#038;p=62502"},"modified":"2024-06-23T15:29:13","modified_gmt":"2024-06-23T12:29:13","slug":"color-soin-hair-colour-azure-black","status":"publish","type":"product","link":"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/","title":{"rendered":"Color &#038; Soin Hair Colour, Azure Black"},"content":{"rendered":"<p>2A\u00a0azure black.<\/p>\n<p>A permanent hair colour with plant extracts. It has been formulated with powerful active ingredients that respect the essential health of the hair.<\/p>\n<p>Thanks to its ammonia-free formula \u2013 it contains <strong>no paraben, resorcin or silicon<\/strong> and is dermatologically tested \u2013 it is perfectly suitable for the most sensitive scalps! More than just a hair colour, it is also a treatment \u2013 its oleo-protein complex has been specially formed to protect the hair structure during the colouring process, thus offering hydration, suppleness and shine!<\/p>\n<p>Color &amp; Soin\u00ae uses the purest, most brilliant pigments in order to master the art of gleaming hair and to create that inexpressible appearance of colour in movement, while covering 100% of grey hair. Easy to apply and with no sharp odour, Color &amp; Soin\u00ae offers maximum user comfort. The result is hair that is bursting with health and a colour that remains fresh &amp; and radiant week after week.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2A\u00a0azure black. A permanent hair colour with plant extracts. It has been formulated with powerful active ingredients that respect the essential health of the hair. Thanks to its ammonia-free formula \u2013 it contains no paraben, resorcin or silicon and is dermatologically tested \u2013 it is perfectly suitable for the most sensitive scalps! More than just a hair colour, it is&hellip;<\/p>\n","protected":false},"featured_media":62507,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[1510,909,889],"product_tag":[],"class_list":{"0":"post-62502","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-hair-dyes-2","7":"product_cat-hair-dyes","8":"product_cat-natural-cosmetics","9":"product_shipping_class-1-en","10":"pa_brand-3chenes","12":"first","13":"instock","14":"purchasable","15":"product-type-simple","16":"col-xs-6 col-sm-4","17":"col-md-3 col-lg-3","18":"un-4-cols"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Color &amp; Soin Hair Colour, Azure Black - Looduspere Organic Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Color &amp; Soin Hair Colour, Azure Black - Looduspere Organic Shop\" \/>\n<meta property=\"og:description\" content=\"2A\u00a0azure black. A permanent hair colour with plant extracts. It has been formulated with powerful active ingredients that respect the essential health of the hair. Thanks to its ammonia-free formula \u2013 it contains no paraben, resorcin or silicon and is dermatologically tested \u2013 it is perfectly suitable for the most sensitive scalps! More than just a hair colour, it is&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/\" \/>\n<meta property=\"og:site_name\" content=\"Looduspere Organic Shop\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/loodusperepood\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-23T12:29:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2015\/11\/color-et-soin-juuksev\u00e4rv-2A.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product\\\/color-soin-hair-colour-azure-black\\\/\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product\\\/color-soin-hair-colour-azure-black\\\/\",\"name\":\"Color & Soin Hair Colour, Azure Black - Looduspere Organic Shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product\\\/color-soin-hair-colour-azure-black\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product\\\/color-soin-hair-colour-azure-black\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/color-et-soin-juuksev\u00e4rv-2A.jpg\",\"datePublished\":\"2016-06-30T12:04:20+00:00\",\"dateModified\":\"2024-06-23T12:29:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product\\\/color-soin-hair-colour-azure-black\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product\\\/color-soin-hair-colour-azure-black\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product\\\/color-soin-hair-colour-azure-black\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/color-et-soin-juuksev\u00e4rv-2A.jpg\",\"contentUrl\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/color-et-soin-juuksev\u00e4rv-2A.jpg\",\"width\":600,\"height\":600,\"caption\":\"Color & Soin Hair Colour, Azure Black\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/product\\\/color-soin-hair-colour-azure-black\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.looduspere.ee\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Color &#038; Soin Hair Colour, Azure Black\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#website\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/\",\"name\":\"Looduspere \u00f6kopood\",\"description\":\"Healthy organic and natural products\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#organization\"},\"alternateName\":\"Looduspere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.looduspere.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#organization\",\"name\":\"Looduspere \u00f6kopood\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/340768897_1025251132216623_8613010291235268142_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.looduspere.ee\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/340768897_1025251132216623_8613010291235268142_n.jpg\",\"width\":1045,\"height\":1045,\"caption\":\"Looduspere \u00f6kopood\"},\"image\":{\"@id\":\"https:\\\/\\\/www.looduspere.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/loodusperepood\",\"https:\\\/\\\/www.instagram.com\\\/looduspere\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Color & Soin Hair Colour, Azure Black - Looduspere Organic Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/","og_locale":"en_US","og_type":"article","og_title":"Color & Soin Hair Colour, Azure Black - Looduspere Organic Shop","og_description":"2A\u00a0azure black. A permanent hair colour with plant extracts. It has been formulated with powerful active ingredients that respect the essential health of the hair. Thanks to its ammonia-free formula \u2013 it contains no paraben, resorcin or silicon and is dermatologically tested \u2013 it is perfectly suitable for the most sensitive scalps! More than just a hair colour, it is&hellip;","og_url":"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/","og_site_name":"Looduspere Organic Shop","article_publisher":"https:\/\/www.facebook.com\/loodusperepood","article_modified_time":"2024-06-23T12:29:13+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2015\/11\/color-et-soin-juuksev\u00e4rv-2A.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/","url":"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/","name":"Color & Soin Hair Colour, Azure Black - Looduspere Organic Shop","isPartOf":{"@id":"https:\/\/www.looduspere.ee\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/#primaryimage"},"image":{"@id":"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/#primaryimage"},"thumbnailUrl":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2015\/11\/color-et-soin-juuksev\u00e4rv-2A.jpg","datePublished":"2016-06-30T12:04:20+00:00","dateModified":"2024-06-23T12:29:13+00:00","breadcrumb":{"@id":"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/#primaryimage","url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2015\/11\/color-et-soin-juuksev\u00e4rv-2A.jpg","contentUrl":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2015\/11\/color-et-soin-juuksev\u00e4rv-2A.jpg","width":600,"height":600,"caption":"Color & Soin Hair Colour, Azure Black"},{"@type":"BreadcrumbList","@id":"https:\/\/www.looduspere.ee\/en\/product\/color-soin-hair-colour-azure-black\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.looduspere.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.looduspere.ee\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Color &#038; Soin Hair Colour, Azure Black"}]},{"@type":"WebSite","@id":"https:\/\/www.looduspere.ee\/#website","url":"https:\/\/www.looduspere.ee\/","name":"Looduspere \u00f6kopood","description":"Healthy organic and natural products","publisher":{"@id":"https:\/\/www.looduspere.ee\/#organization"},"alternateName":"Looduspere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.looduspere.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.looduspere.ee\/#organization","name":"Looduspere \u00f6kopood","url":"https:\/\/www.looduspere.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.looduspere.ee\/#\/schema\/logo\/image\/","url":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2025\/01\/340768897_1025251132216623_8613010291235268142_n.jpg","contentUrl":"https:\/\/www.looduspere.ee\/wp-content\/uploads\/2025\/01\/340768897_1025251132216623_8613010291235268142_n.jpg","width":1045,"height":1045,"caption":"Looduspere \u00f6kopood"},"image":{"@id":"https:\/\/www.looduspere.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loodusperepood","https:\/\/www.instagram.com\/looduspere\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/product\/62502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/comments?post=62502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/media\/62507"}],"wp:attachment":[{"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/media?parent=62502"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/product_cat?post=62502"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.looduspere.ee\/en\/wp-json\/wp\/v2\/product_tag?post=62502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}